{"id":181,"count":3,"description":"","link":"https:\/\/magarinos.eu\/atandocabos\/blog\/category\/apellidos\/herreros-de-tejada\/","name":"Herreros de Tejada","slug":"herreros-de-tejada","taxonomy":"category","parent":158,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Herreros de Tejada archivos - Atando Cabos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/magarinos.eu\/atandocabos\/blog\/category\/apellidos\/herreros-de-tejada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Herreros de Tejada archivos - Atando Cabos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magarinos.eu\/atandocabos\/blog\/category\/apellidos\/herreros-de-tejada\/\" \/>\n<meta property=\"og:site_name\" content=\"Atando Cabos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/blog\\\/category\\\/apellidos\\\/herreros-de-tejada\\\/\",\"url\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/blog\\\/category\\\/apellidos\\\/herreros-de-tejada\\\/\",\"name\":\"Herreros de Tejada archivos - Atando Cabos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/blog\\\/category\\\/apellidos\\\/herreros-de-tejada\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/blog\\\/category\\\/apellidos\\\/herreros-de-tejada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apellidos\",\"item\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/blog\\\/category\\\/apellidos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Herreros de Tejada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/#website\",\"url\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/\",\"name\":\"Atando Cabos\",\"description\":\"Una p\u00e1gina web de la familia Magari\u00f1os Ram\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/#organization\",\"name\":\"Atando Cabos\",\"url\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-cropped-Caballero_Anciano.jpg\",\"contentUrl\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-cropped-Caballero_Anciano.jpg\",\"width\":512,\"height\":512,\"caption\":\"Atando Cabos\"},\"image\":{\"@id\":\"https:\\\/\\\/magarinos.eu\\\/atandocabos\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Herreros de Tejada archivos - Atando Cabos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/magarinos.eu\/atandocabos\/blog\/category\/apellidos\/herreros-de-tejada\/","og_locale":"es_ES","og_type":"article","og_title":"Herreros de Tejada archivos - Atando Cabos","og_url":"https:\/\/magarinos.eu\/atandocabos\/blog\/category\/apellidos\/herreros-de-tejada\/","og_site_name":"Atando Cabos","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/magarinos.eu\/atandocabos\/blog\/category\/apellidos\/herreros-de-tejada\/","url":"https:\/\/magarinos.eu\/atandocabos\/blog\/category\/apellidos\/herreros-de-tejada\/","name":"Herreros de Tejada archivos - Atando Cabos","isPartOf":{"@id":"https:\/\/magarinos.eu\/atandocabos\/#website"},"breadcrumb":{"@id":"https:\/\/magarinos.eu\/atandocabos\/blog\/category\/apellidos\/herreros-de-tejada\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/magarinos.eu\/atandocabos\/blog\/category\/apellidos\/herreros-de-tejada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/magarinos.eu\/atandocabos\/"},{"@type":"ListItem","position":2,"name":"Apellidos","item":"https:\/\/magarinos.eu\/atandocabos\/blog\/category\/apellidos\/"},{"@type":"ListItem","position":3,"name":"Herreros de Tejada"}]},{"@type":"WebSite","@id":"https:\/\/magarinos.eu\/atandocabos\/#website","url":"https:\/\/magarinos.eu\/atandocabos\/","name":"Atando Cabos","description":"Una p\u00e1gina web de la familia Magari\u00f1os Ram\u00f3n","publisher":{"@id":"https:\/\/magarinos.eu\/atandocabos\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magarinos.eu\/atandocabos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/magarinos.eu\/atandocabos\/#organization","name":"Atando Cabos","url":"https:\/\/magarinos.eu\/atandocabos\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/magarinos.eu\/atandocabos\/#\/schema\/logo\/image\/","url":"https:\/\/magarinos.eu\/atandocabos\/wp-content\/uploads\/2022\/06\/cropped-cropped-Caballero_Anciano.jpg","contentUrl":"https:\/\/magarinos.eu\/atandocabos\/wp-content\/uploads\/2022\/06\/cropped-cropped-Caballero_Anciano.jpg","width":512,"height":512,"caption":"Atando Cabos"},"image":{"@id":"https:\/\/magarinos.eu\/atandocabos\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/magarinos.eu\/atandocabos\/wp-json\/wp\/v2\/categories\/181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magarinos.eu\/atandocabos\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/magarinos.eu\/atandocabos\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/magarinos.eu\/atandocabos\/wp-json\/wp\/v2\/categories\/158"}],"wp:post_type":[{"href":"https:\/\/magarinos.eu\/atandocabos\/wp-json\/wp\/v2\/posts?categories=181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}